{"id":29280,"date":"2012-01-30T00:00:00","date_gmt":"2012-01-30T05:00:00","guid":{"rendered":"https:\/\/cursosdeia.com.co\/?post_type=publicaciones&#038;p=29280"},"modified":"2025-06-13T11:02:48","modified_gmt":"2025-06-13T16:02:48","slug":"panorama-general-del-sector-electrico-en-america-latina-y-el-caribe","status":"publish","type":"publicaciones","link":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/","title":{"rendered":"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe"},"content":{"rendered":"<p>2012 \u2013 Electricity consumption in Latin America and the Caribbean. The supply of electrical energy in Latin America and the Caribbean. Distributed generation. Smart grids \u2013 smart grids. Regional electrical integration. (Available only in Spanish)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2012 \u2013 Electricity consumption in Latin America and the Caribbean. The supply of electrical energy in Latin America and the Caribbean. Distributed generation. Smart grids \u2013 smart grids. Regional electrical integration. (Available only in Spanish)<\/p>\n","protected":false},"author":3,"featured_media":22099,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[122],"tags":[],"class_list":["post-29280","publicaciones","type-publicaciones","status-publish","format-standard","has-post-thumbnail","hentry","category-institutional-publications"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v23.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe - OLACDE<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe\" \/>\n<meta property=\"og:description\" content=\"2012 \u2013 Electricity consumption in Latin America and the Caribbean. The supply of electrical energy in Latin America and the Caribbean. Distributed generation. Smart grids \u2013 smart grids. Regional electrical integration. (Available only in Spanish)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/\" \/>\n<meta property=\"og:site_name\" content=\"OLACDE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OLADEORG\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T16:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OLADEORG\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/\",\"url\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/\",\"name\":\"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe - OLACDE\",\"isPartOf\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg\",\"datePublished\":\"2012-01-30T05:00:00+00:00\",\"dateModified\":\"2025-06-13T16:02:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage\",\"url\":\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg\",\"contentUrl\":\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg\",\"width\":1024,\"height\":511},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cursosdeia.com.co\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaciones\",\"item\":\"https:\/\/cursosdeia.com.co\/en\/publicaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#website\",\"url\":\"https:\/\/cursosdeia.com.co\/en\/\",\"name\":\"OLADE\",\"description\":\"La Organizaci\u00f3n Latinoamericana y Caribe\u00f1a de Energ\u00eda\",\"publisher\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cursosdeia.com.co\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#organization\",\"name\":\"OLADE\",\"url\":\"https:\/\/cursosdeia.com.co\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2024\/03\/Logo-OLADE-WEB_Color.png\",\"contentUrl\":\"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2024\/03\/Logo-OLADE-WEB_Color.png\",\"width\":300,\"height\":132,\"caption\":\"OLADE\"},\"image\":{\"@id\":\"https:\/\/cursosdeia.com.co\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OLADEORG\",\"https:\/\/x.com\/OLADEORG\",\"https:\/\/www.youtube.com\/user\/oladeorg\",\"https:\/\/www.instagram.com\/oladealc\/\",\"https:\/\/www.linkedin.com\/company\/olade\/\"],\"description\":\"La Organizaci\u00f3n Latinoamericana de Energ\u00eda (OLADE) es un organismo de cooperaci\u00f3n, coordinaci\u00f3n y asesor\u00eda t\u00e9cnica, de car\u00e1cter p\u00fablico intergubernamental, constituido el 2 de noviembre de 1973 mediante la suscripci\u00f3n del Convenio de Lima, ratificado por 27 pa\u00edses de Am\u00e9rica Latina y El Caribe, con el objetivo fundamental de fomentar la integraci\u00f3n, conservaci\u00f3n, racional aprovechamiento, comercializaci\u00f3n y defensa de los recursos energ\u00e9ticos de la Regi\u00f3n.\",\"email\":\"info@cursosdeia.com.co\",\"telephone\":\"+59322598122\",\"legalName\":\"Organizaci\u00f3n Latinoamericana de Energ\u00eda\",\"foundingDate\":\"1973-11-02\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe - OLACDE","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe","og_description":"2012 \u2013 Electricity consumption in Latin America and the Caribbean. The supply of electrical energy in Latin America and the Caribbean. Distributed generation. Smart grids \u2013 smart grids. Regional electrical integration. (Available only in Spanish)","og_url":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/","og_site_name":"OLACDE","article_publisher":"https:\/\/www.facebook.com\/OLADEORG","article_modified_time":"2025-06-13T16:02:48+00:00","og_image":[{"width":1024,"height":511,"url":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OLADEORG","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/","url":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/","name":"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe - OLACDE","isPartOf":{"@id":"https:\/\/cursosdeia.com.co\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage"},"image":{"@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage"},"thumbnailUrl":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg","datePublished":"2012-01-30T05:00:00+00:00","dateModified":"2025-06-13T16:02:48+00:00","breadcrumb":{"@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#primaryimage","url":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg","contentUrl":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2012\/01\/panorama-general-sector-electrico.jpg","width":1024,"height":511},{"@type":"BreadcrumbList","@id":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/panorama-general-del-sector-electrico-en-america-latina-y-el-caribe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cursosdeia.com.co\/en\/"},{"@type":"ListItem","position":2,"name":"Publicaciones","item":"https:\/\/cursosdeia.com.co\/en\/publicaciones\/"},{"@type":"ListItem","position":3,"name":"Panorama general del sector el\u00e9ctrico en Am\u00e9rica Latina y el Caribe"}]},{"@type":"WebSite","@id":"https:\/\/cursosdeia.com.co\/en\/#website","url":"https:\/\/cursosdeia.com.co\/en\/","name":"OLADE","description":"La Organizaci\u00f3n Latinoamericana y Caribe\u00f1a de Energ\u00eda","publisher":{"@id":"https:\/\/cursosdeia.com.co\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursosdeia.com.co\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cursosdeia.com.co\/en\/#organization","name":"OLADE","url":"https:\/\/cursosdeia.com.co\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cursosdeia.com.co\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2024\/03\/Logo-OLADE-WEB_Color.png","contentUrl":"https:\/\/cursosdeia.com.co\/wp-content\/uploads\/2024\/03\/Logo-OLADE-WEB_Color.png","width":300,"height":132,"caption":"OLADE"},"image":{"@id":"https:\/\/cursosdeia.com.co\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OLADEORG","https:\/\/x.com\/OLADEORG","https:\/\/www.youtube.com\/user\/oladeorg","https:\/\/www.instagram.com\/oladealc\/","https:\/\/www.linkedin.com\/company\/olade\/"],"description":"La Organizaci\u00f3n Latinoamericana de Energ\u00eda (OLADE) es un organismo de cooperaci\u00f3n, coordinaci\u00f3n y asesor\u00eda t\u00e9cnica, de car\u00e1cter p\u00fablico intergubernamental, constituido el 2 de noviembre de 1973 mediante la suscripci\u00f3n del Convenio de Lima, ratificado por 27 pa\u00edses de Am\u00e9rica Latina y El Caribe, con el objetivo fundamental de fomentar la integraci\u00f3n, conservaci\u00f3n, racional aprovechamiento, comercializaci\u00f3n y defensa de los recursos energ\u00e9ticos de la Regi\u00f3n.","email":"info@cursosdeia.com.co","telephone":"+59322598122","legalName":"Organizaci\u00f3n Latinoamericana de Energ\u00eda","foundingDate":"1973-11-02","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/publicaciones\/29280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/publicaciones"}],"about":[{"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/types\/publicaciones"}],"author":[{"embeddable":true,"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/media\/22099"}],"wp:attachment":[{"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/media?parent=29280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/categories?post=29280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursosdeia.com.co\/en\/wp-json\/wp\/v2\/tags?post=29280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}